{"id":8182,"date":"2015-11-02T13:29:41","date_gmt":"2015-11-02T18:29:41","guid":{"rendered":"http:\/\/www.runottawa.ca\/?p=8182"},"modified":"2015-11-19T14:10:28","modified_gmt":"2015-11-19T19:10:28","slug":"je-viens-de-minscrire-au-marathon-le-guide-de-survie","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/","title":{"rendered":"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb &#8211; le guide de survie"},"content":{"rendered":"<p>\u00c7a y est.<\/p>\n<p>Que vous l\u2019ayez fait seul, avec un ami ou une amie ou comme \u00e9quipe, vous avez r\u00e9serv\u00e9 votre dossard pour le Marathon d\u2019Ottawa Banque Scotia, le 29 mai 2016.<\/p>\n<p>Comment vous sentez-vous ? Pomp\u00e9 \u00e0 bloc ? Un peu craintif ? Ne stressez pas trop, parce qu\u2019il reste encore un peu plus de 7 mois avant le jour de la course et beaucoup de temps pour l\u2019entra\u00eenement.<\/p>\n<p>Que vous vous appr\u00eatiez \u00e0 couvrir la distance pour la premi\u00e8re fois ou que vous soyez un coureur d\u2019exp\u00e9rience qui cherche \u00e0 \u00e9tablir un nouveau record personnel, nous avons compil\u00e9 une liste de conseils pour vous aider \u00e0 vous mettre dans la meilleure forme possible pour la course \u00e0 l\u2019arriv\u00e9e du printemps.<\/p>\n<h2>Trouvez votre motivation<\/h2>\n<p>Il est difficile de s\u2019engager \u00e0 faire une course qui est encore si loin dans le temps, et c\u2019est pourquoi vous avez besoin de trouver une source de motivation qui va vous coller \u00e0 la peau.<\/p>\n<p>Ce pourrait \u00eatre d\u2019am\u00e9liorer votre sant\u00e9 et votre forme physique, de rayer un but de la liste de r\u00eaves, ou d\u2019atteindre ce meilleur chrono personnel qu\u2019on vient de mentionner. Vos raisons pourraient \u00eatre diff\u00e9rentes de celles de n\u2019importe qui d\u2019autre ; l\u2019important, c\u2019est qu\u2019elles aient un sens pour vous.<\/p>\n<p>Allez revoir quelques-uns de <a href=\"https:\/\/www.runottawa.ca\/fr\/march-momentum-tips-maintaining-motivation\/\" target=\"_blank\">nos anciens articles<\/a> sur la <a href=\"https:\/\/www.runottawa.ca\/fr\/resolution-action-achieving-running-goals-2013\/\" target=\"_blank\">fa\u00e7on de rester motiv\u00e9.<\/a><\/p>\n<p>Une autre fa\u00e7on de rester sur la voie, c\u2019est de trouver une cause qui vous tient \u00e0 c\u0153ur et de vous inscrire au <a href=\"https:\/\/www.runottawa.ca\/fr\/les-courses\/fin-de-semaine-des-courses-tamarack-dottawa\/informations\/defi-caritatif-banque-scotia\/\" target=\"_blank\">D\u00e9fi caritatif Banque Scotia<\/a>. Recueillir des fonds tout en vous entra\u00eenant est une excellente fa\u00e7on de vous tenir responsable vis-\u00e0-vis votre objectif ; demandez seulement aux coureurs qui ont ramass\u00e9 plus de 800 000 $ pour les \u0153uvres caritatives locales et nationales l\u2019an pass\u00e9 !<\/p>\n<h2>Faire un plan<\/h2>\n<p>Maintenant que vous avez votre ou vos raison(s), vous avez besoin d\u2019un plan \u00e0 suivre. Il existe de nombreux plans d\u2019entra\u00eenement pour le marathon qui ne sont qu\u2019\u00e0 une recherche Google et \u00e0 quelques clics de distance, mais il peut \u00eatre difficile de faire un choix.<\/p>\n<p>Pour qu\u2019il soit un peu plus facile de faire votre choix, vous devez tenir compte de votre objectif (distance, vitesse ou les deux), de votre niveau relatif de forme physique et du temps dont vous disposez. Quel que soit le plan que vous finissez par choisir, plusieurs vont vous faire courir :<\/p>\n<ul>\n<li>Des courses de distance pour l\u2019endurance<\/li>\n<li>Des courses \u2018tempo\u2019 pour la vitesse et la cadence<\/li>\n<li>Des collines pour la puissance<\/li>\n<li>Des \u2018intervalles\u2019 pour la vitesse et la versatilit\u00e9<\/li>\n<li>De l\u2019entra\u00eenement polyvalent<\/li>\n<\/ul>\n<p>Consultez quelques-uns des programme et des calendriers d\u2019entra\u00eenement sur des sites populaires comme <a href=\"http:\/\/www.runnersworld.co.uk\/general\/big-marathon-index\/7355.html\" target=\"_blank\">Runner\u2019s World<\/a> ou <a href=\"http:\/\/www.coolrunning.com\/engine\/2\/2_4\/143.shtml\" target=\"_blank\">Cool Running<\/a> pour avoir une id\u00e9e de ce que vous devez faire.<\/p>\n<p>Une autre option serait de vous procurer un plan sur mesure et une \u00e9valuation de forme physique d\u2019une organisation locale comme <a href=\"https:\/\/www.peakcentre.ca\/\" target=\"_blank\">Peak Centre<\/a>, au sujet de laquelle nous ferons bient\u00f4t un article.<\/p>\n<h2>Mettez-vous y<\/h2>\n<p>C\u2019est la partie o\u00f9 vous lacez vraiment vos chaussures et que vous prenez le dehors. Il y a beaucoup de kilom\u00e8tres entre vous et la ligne de d\u00e9part ; alors, commencez \u00e0 vous y attaquer comme vous mangeriez un \u00e9l\u00e9phant, une bouch\u00e9e \u00e0 la fois.<\/p>\n<p>Si la course en solo ne vous attire pas vraiment (particuli\u00e8rement pour ces longues courses du dimanche matin), trouvez-vous un groupe d\u2019entra\u00eenement local avec qui courir. \u00c7a peut faire des merveilles pour vous garder responsable, et rendre ces courses plus amusantes. Allez voir <a href=\"https:\/\/www.runottawa.ca\/fr\/au-sujet-de-courez-ottawa\/membres\/\" target=\"_blank\">le club Courez Ottawa<\/a>, <a href=\"http:\/\/www.runningroom.com\/hm\/\" target=\"_blank\">the Running Room<\/a> ou le <a href=\"http:\/\/www.ottawarunningclub.com\/\" target=\"_blank\">Ottawa Running Club<\/a> pour trouver un groupe pr\u00e8s de chez vous.<\/p>\n<p>Une autre excellente fa\u00e7on de rester motiv\u00e9, c\u2019est de vous inscrire \u00e0 d\u2019autres courses chemin faisant. La course est une incroyable activit\u00e9 sociale et faire des courses est une excellente fa\u00e7on de rencontrer de nouveaux amis et partenaires d\u2019entra\u00eenement. Consultez l<a href=\"https:\/\/www.runottawa.ca\/fr\/les-courses\/calendrier-des-activites\/\" target=\"_blank\">e calendrier des courses de Courez Ottawa<\/a> pour voir les courses \u00e0 venir (comme notre 5K gratuit, le 5 d\u00e9cembre).<\/p>\n<h2>Tout est dans les d\u00e9tails<\/h2>\n<p>S\u2019entra\u00eener pour un marathon, \u00e7a ne concerne pas seulement les kilom\u00e8tres que vous accumulez sur vos chaussures. Il s\u2019agit aussi de ma\u00eetriser votre r\u00e9gime alimentaire et \u00e9viter les blessures.<\/p>\n<p>Quand vous investissez autant de temps et d\u2019\u00e9nergie dans l\u2019exercice et l\u2019entra\u00eenement, vous avec besoin de vous assurer mettre une partie de cette \u00e9nergie \u00e0 penser \u00e0 comment vous mangez. Vous pouvez lire cet article de la nutritionniste locale Elizabeth Mansfield sur <a href=\"https:\/\/www.runottawa.ca\/fr\/abc-de-la-nutrition-adaptee-a-la-course\/\" target=\"_blank\">comment commencer avec une nutrition adapt\u00e9 \u00e0 la course.<\/a><\/p>\n<p>Les blessures de course peuvent \u00eatre une source de frustration. Mais, avec un temps ad\u00e9quat de repos et de r\u00e9cup\u00e9ration de votre entra\u00eenement, la plupart de celles-ci peuvent \u00eatre \u00e9vit\u00e9es. Lisez cet article de la massoth\u00e9rapeute sportive Paula Burchat sur <a href=\"https:\/\/www.runottawa.ca\/fr\/injury-prevention-winter-weather-training\/\">comment tirer le meilleur parti de l\u2019entra\u00eenement d\u2019hiver tout en demeurant libre de blessures.<\/a><\/p>\n<h2>Pr\u00eats pour un 42,2?<\/h2>\n<p>Il se peut que nous soyons un peu partiaux, mais compl\u00e9ter un marathon est l\u2019une des choses les plus satisfaisantes \u00e0 rayer du la liste des choses \u00e0 faire \u00e0 tout prix. Si vous suivez ces conseils, vous saurez de quoi nous parlons le 29 mai.<\/p>\n<p>Un conseil que nous avons rat\u00e9 ? Partagez-le avec nous sur <a href=\"https:\/\/twitter.com\/ottawamarathon\" target=\"_blank\">Twitter<\/a> ou <a href=\"https:\/\/www.facebook.com\/ottawamarathon\" target=\"_blank\">Facebook.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c7a y est. Que vous l\u2019ayez fait seul, avec un ami ou une amie ou [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-8182","post","type-post","status-publish","format-standard","hentry","category-entrainement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb - le guide de survie - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb &#8211; le guide de survie\",\"datePublished\":\"2015-11-02T18:29:41+00:00\",\"dateModified\":\"2015-11-19T19:10:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/\"},\"wordCount\":917,\"articleSection\":[\"Entra\u00eenement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/\",\"name\":\"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb - le guide de survie - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-11-02T18:29:41+00:00\",\"dateModified\":\"2015-11-19T19:10:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb &#8211; le guide de survie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb - le guide de survie - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb &#8211; le guide de survie","datePublished":"2015-11-02T18:29:41+00:00","dateModified":"2015-11-19T19:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/"},"wordCount":917,"articleSection":["Entra\u00eenement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/","url":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/","name":"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb - le guide de survie - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2015-11-02T18:29:41+00:00","dateModified":"2015-11-19T19:10:28+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/je-viens-de-minscrire-au-marathon-le-guide-de-survie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab Je viens de m\u2019inscrire au marathon ! \u00bb &#8211; le guide de survie"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/8182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=8182"}],"version-history":[{"count":2,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/8182\/revisions"}],"predecessor-version":[{"id":8196,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/8182\/revisions\/8196"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=8182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=8182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=8182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}