{"id":6457,"date":"2015-05-19T18:42:37","date_gmt":"2015-05-19T22:42:37","guid":{"rendered":"http:\/\/www.runottawa.ca\/?p=6457"},"modified":"2017-07-21T11:44:31","modified_gmt":"2017-07-21T15:44:31","slug":"le-pouvoir-des-encouragement","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/","title":{"rendered":"Le pouvoir des encouragement"},"content":{"rendered":"<p><em>\u201c\u2019Tu arrives pr\u00e8s du pont de retour vers l\u2019Ontario\u2026 Je peux voir la c\u00f4te\u2026 Ne reste que 5km\u2026 Tu y es presque\u2026 Allez continue\u2026 ugh j\u2019ai mal aux jambes\u2026!\u201d <\/em><\/p>\n<p><em>C\u2019\u00e9tait ce qui passait par la t\u00eate de Hank Devos en courant le demi-marathon pour la premi\u00e8re fois l\u2019an dernier.<\/em><\/p>\n<p>\u201cRendu l\u00e0, j\u2019\u00e9tais extr\u00eamement fatigue et j\u2019essayais de g\u00e9rer mes niveaux de glucose de sang, explique-t-il. Mais en voyant les gens sur les c\u00f4t\u00e9s, t\u2019encourageant, \u00e7a te donne la pouss\u00e9e dont tu as besoin pour passer \u00e0 travers le prochain kilom\u00e8tre.\u00a0\u00bb<\/p>\n<p>Hank est un des coureurs \u00e0 Otttawa de l\u2019\u00e9quipe 2015 Connect in Motion pour le <a href=\"https:\/\/www.runottawa.ca\/races-and-events\/tamarack-ottawa-race-weekend\/weekend-information\/scotiabank-charity-challenge\/\">D\u00e9fi caritatif Banque Scotia<\/a>, dans le cadre du fin de semaine des courses Ottawa Tamarac. Il est aussi atteint du diab\u00e8te de type 1 et courra sont premier marathon cette ann\u00e9e.<\/p>\n<p>La plupart des gens n\u2019ont pas vraiment d\u2019id\u00e9e de ce que signifie vivre avec un diab\u00e8te de type 1, ils pensent que vous vous injectez une dose d\u2019insuline et que \u00e7a fait le travail \u2013 mais c\u2019est beaucoup plus complexe. Tous les jours, c\u2019est un tiraillement entre la nourriture, les hormones de stress, l\u2019exercice, les niveaux de glucose dans le sang et le dosage d\u2019insuline, et ce, simplement pour te garder dans un param\u00e8tre optimal.<\/p>\n<p>Pas une heure n\u2019est pareille \u00e0 la pr\u00e9c\u00e9dente.<\/p>\n<p>L\u2019exercice est un des \u00e9l\u00e9ments les plus compliqu\u00e9s \u00e0 g\u00e9rer. Une personne avec un type 1 doit tenter de copier ce que le syst\u00e8me physiologique de son corps fait \u00e0 tout moment de la journ\u00e9e.<\/p>\n<p>C\u2019est un constant effort de calibration. Comme le sait Hank et la plupart des coureurs, le meilleur plan de course prend souvent le bord le jour de la course \u00e0 cause d\u2019un probl\u00e8me ou d\u2019un autre. Des fois, \u00e7a se fait tout seul, d\u2019autre fois c\u2019est la gal\u00e8re.<\/p>\n<p>Les gens qui encouragent et les stations d\u2019encouragements partout sur le parcours du fin de semaine des courses donnent un souffl\u00e9 d\u2019\u00e9nergie, de fiert\u00e9 et un peu d\u2019amusement qui poussent les coureurs en avant. Au cours des quatre derni\u00e8res ann\u00e9es. <a href=\"http:\/\/www.connectedinmotion.ca\/teamcim\/\">Connected in Motion<\/a> a plac\u00e9 une de ces stations au coin de Queen Elizabeth et McLeod. Cette ann\u00e9e ne sera pas en reste \u2013 nous sommes engag\u00e9s \u00e0 encourager tant les coureurs de notre propre \u00e9quipe que tous les coureurs des \u00e9v\u00e9nements de cette ann\u00e9e.<\/p>\n<p>Nous comprenons bien la valeur de se soutenir l\u2019un l\u2019autre dans nos vies quotidiennes avec le diab\u00e8te et nous avons appliqu\u00e9 ce m\u00eame principe \u00e0 notre station d\u2019encouragement. Nous sommes tr\u00e8s fiers de notre station en la rendant un endroit o\u00f9 il fait bon passer du temps pendant le weekend. Nous faisons jouer de la bonne musique, nous avons une station pour pr\u00e9parer des pancartes, nous fournissions du ravitaillement et des grignotines \u00e0 notre \u00e9quipe et bien s\u00fbr, nous sommes l\u00e0 pour encourager jusqu\u2019au tout dernier coureur!<\/p>\n<p>Cette ann\u00e9e, pour notre participation au D\u00e9fi caritatif Banque Scotia, l\u2019objectif de Connected in Motion est d\u2019amasser 15\u00a0000$. Les membres de notre <a href=\"http:\/\/www.connectedinmotion.ca\/teamcim\/\">\u00c9quipeCIM<\/a> travaille fort pour nous aider \u00e0 atteindre cet objectif. Nous avons un weekend entier d\u2019\u00e9v\u00e9nements planifi\u00e9s pour soutenir notre \u00e9quipe, \u00e0 commencer par notre Mix N\u2019Mingle vendredi soir \u00e0 Millstreet Brew Pub et notre Souper pique-nique \u00c9quipeCIM apr\u00e8s les courses de 5km et 10km, \u00e0 notre station d\u2019encouragement. Venez y faire un tour pour voir ce qu\u2019on pr\u00e9pare! Pour faire un don, vous pouvez visiter notre page du D\u00e9fi caritatif Banque Scotia et <a href=\"https:\/\/secure.e2rm.com\/registrant\/LocationHome.aspx?eventid=154326&amp;langpref=en-CA&amp;locationID=155895&amp;Referrer=direct%2fnone\">nous commanditer!<\/a><\/p>\n<p>Si vous souhaitez en savoir plus sur Connected in Motion et nos \u00e9v\u00e9nements du fin de semaine de courses Ottawa Tamarac, visitez notre site web &#8211; <a href=\"http:\/\/www.connectedinmotion.ca\">www.connectedinmotion.ca<\/a><\/p>\n<p><a href=\"http:\/\/www.connectedinmotion.ca\/\"><em>Connected In Motion<\/em><\/a><em>, un organisme caritatif incorpor\u00e9 fond\u00e9 en 2008, dont la mission est de b\u00e2tir une communaut\u00e9 d\u2019adultes vivant avec le diab\u00e8tes de type 1par l\u2019\u00e9ducation exp\u00e9rientielle du diab\u00e8tes par les pairs, l\u2019activit\u00e9 physique et les aventures ext\u00e9rieures pour qu\u2019ils s\u2019inspirent l\u2019un l\u2019autre \u00e0 vivre sans limites. Leur vision est de cr\u00e9er une communaut\u00e9 d\u2019adultes en sant\u00e9, actifs, \u00e9duqu\u00e9s vivant avec le diab\u00e8tes de type 1 qui sont soutenus et engag\u00e9s dans l\u2019autogestion du diab\u00e8tes. <\/em><br \/>\n<em>Auteure: <\/em><a href=\"http:\/\/www.connectedinmotion.ca\/our-team\/\"><em>Julie DeVos<\/em><\/a><em> \u2013 <\/em><em>Directrice de programme pour Connected In Motion &#8211; T1D depuis 25 ans.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u2019Tu arrives pr\u00e8s du pont de retour vers l\u2019Ontario\u2026 Je peux voir la c\u00f4te\u2026 Ne [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[107],"tags":[108],"class_list":["post-6457","post","type-post","status-publish","format-standard","hentry","category-communaute","tag-defi-caritatif-banque-scotia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le pouvoir des encouragement - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Le pouvoir des encouragement\",\"datePublished\":\"2015-05-19T22:42:37+00:00\",\"dateModified\":\"2017-07-21T15:44:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/\"},\"wordCount\":771,\"keywords\":[\"D\u00e9fi caritatif Banque Scotia\"],\"articleSection\":[\"Communaut\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/\",\"name\":\"Le pouvoir des encouragement - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-05-19T22:42:37+00:00\",\"dateModified\":\"2017-07-21T15:44:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/le-pouvoir-des-encouragement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le pouvoir des encouragement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le pouvoir des encouragement - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Le pouvoir des encouragement","datePublished":"2015-05-19T22:42:37+00:00","dateModified":"2017-07-21T15:44:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/"},"wordCount":771,"keywords":["D\u00e9fi caritatif Banque Scotia"],"articleSection":["Communaut\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/","url":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/","name":"Le pouvoir des encouragement - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2015-05-19T22:42:37+00:00","dateModified":"2017-07-21T15:44:31+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/le-pouvoir-des-encouragement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le pouvoir des encouragement"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/6457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=6457"}],"version-history":[{"count":2,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/6457\/revisions"}],"predecessor-version":[{"id":6459,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/6457\/revisions\/6459"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=6457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=6457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=6457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}