{"id":5324,"date":"2015-02-20T11:41:52","date_gmt":"2015-02-20T16:41:52","guid":{"rendered":"http:\/\/www.runottawa.ca\/?p=5324"},"modified":"2015-02-20T12:16:37","modified_gmt":"2015-02-20T17:16:37","slug":"galettes-de-sarrasin-pour-la-longue-distance","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/","title":{"rendered":"Galettes de sarrasin pour la longue distance"},"content":{"rendered":"<p>La course de longue distance d\u2019hiver a quelque chose qui nous fait vouloir manger des galettes. Des tas et des tas de galettes (apr\u00e8s une quantit\u00e9 appropri\u00e9e d\u2019\u00e9tirage, bien s\u00fbr). H\u00e9 bien, nous parcourions le magnifique livre \u00e9lectronique de Kate Percy <a href=\"http:\/\/www.amazon.com\/FuelSmart-Race-Day-Carbo-load-Triathletes-ebook\/dp\/B009E1ICDS\/ref=sr_1_1?ie=UTF8&amp;qid=1423752113&amp;sr=8-1&amp;keywords=fuelsmart+for+race+day\">FuelSmart for Race Day<\/a> et nous avons trouv\u00e9 de formidables des \u00ab\u00a0galettes bretonnes\u00a0\u00bb, une variation sur la vieille recette de cr\u00eapes.<\/p>\n<p>C\u2019est en effet une recette \u00ab\u00a0\u00e0 longue course\u00a0\u00bb parce qu\u2019elle fonctionne \u00e0 son meilleur si vous laissez la p\u00e2te reposer quelques heures. Alors, faites le m\u00e9lange, mettez-le au frigo, et quand vous rentrerez et ferez le compte de vos kilom\u00e8tres, faites quelques-unes de ces galettes d\u00e9licieux de style cr\u00eape. Nous avons suivi l\u2019option jambon et fromage sugg\u00e9r\u00e9e par Percy (et avons aussi ajout\u00e9 du sirop d\u2019\u00e9rable, naturellement), mais nous pouvons seulement imaginer quel plaisir ce sera de remplir ces cr\u00eapes de toutes sortes de bonnes choses.<\/p>\n<p>Ce qui suit est reproduit avec permission de <a href=\"http:\/\/www.amazon.com\/FuelSmart-Race-Day-Carbo-load-Triathletes-ebook\/dp\/B009E1ICDS\/ref=sr_1_1?ie=UTF8&amp;qid=1423752113&amp;sr=8-1&amp;keywords=fuelsmart+for+race+day\">FuelSmart for Race Day<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Galettes de sarrasin au jambon et fromage<\/strong><\/p>\n<p>Par Kate Percy<\/p>\n<p>Malgr\u00e9 son nom, le sarrasin est un membre de la famille de la rhubarbe et n\u2019a absolument rien \u00e0 voir avec le bl\u00e9. Il est naturellement sans gluten et a une saveur d\u2019amande d\u00e9licieusement douce. On l\u2019utilise traditionnellement en Bretagne dans les galettes de sarrasin ou les traditionnelles \u00ab\u00a0plugs de buckwit\u00a0\u00bb.<\/p>\n<p>Les galettes bretonnes sont splendides \u00e0 manger imm\u00e9diatement apr\u00e8s une longue course pour refaire le plein des r\u00e9serves \u00e9puis\u00e9es de glycog\u00e8ne et de min\u00e9raux perdus par la sueur (pr\u00e9parez le m\u00e9lange avant de partir) et peuvent \u00eatre fourr\u00e9es de n\u2019importe quelles pr\u00e9parations. Vous pourriez essayer cette recette avec des pr\u00e9parations savoureuses traditionnelles, comme des tranches de Brie, de fromage de ch\u00e8vre, du saumon fum\u00e9, des oignons caram\u00e9lis\u00e9s ou des \u0153ufs, ou avec des pr\u00e9parations sucr\u00e9es \u2013 les bananes et le sirop sont l\u2019une de mes pr\u00e9f\u00e9r\u00e9es.<\/p>\n<p>Le sarrasin est \u00e9galement une tr\u00e8s bonne source de mangan\u00e8se, de magn\u00e9sium et de fibre di\u00e9t\u00e9tique. Il contient des flavono\u00efdes et des prot\u00e9ines de bonne qualit\u00e9, et on dit qu\u2019il contr\u00f4le les niveaux de glyc\u00e9mie sanguine.<\/p>\n<p>Temps de pr\u00e9paration\u00a0: 5 minutes<\/p>\n<p>Temps de cuisson\u00a0: 5 minutes<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingr\u00e9dients\u00a0: <\/strong><\/p>\n<p>\u00be tasse (200ml) de farine de sarrasin<\/p>\n<p>\u00bd tasse (125ml) de farine ordinaire (bl\u00e9 entier ou blanche)<\/p>\n<p>1 pinc\u00e9e de sel<\/p>\n<p>1 \u0153uf<\/p>\n<p>\u00bd tasse (125ml) de lait<\/p>\n<p>1 tasse (250ml) d\u2019eau (en ajouter un peu si la p\u00e2te est trop \u00e9paisse)<\/p>\n<p>2 c. \u00e0 table de beurre fondu, quantit\u00e9 suppl\u00e9mentaire pour la cuisson<\/p>\n<p>1 tasse (250ml) de fromage<\/p>\n<p>8-10 tranches de jambon cuit de bonne qualit\u00e9<\/p>\n<p>&nbsp;<\/p>\n<p>Fait 8-10 cr\u00eapes<\/p>\n<p>Kcal 383 cal<\/p>\n<p>Glucides 35 g<\/p>\n<p>Prot\u00e9ines 28g<\/p>\n<p>Gras 17g (8g satur\u00e9s)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Instructions\u00a0:<\/strong><\/p>\n<ol>\n<li>M\u00e9langer le sarrasin et la farine ordinaire, ajouter une pinc\u00e9e de sel et faire un petit creux au centre.<\/li>\n<li>Casser l\u2019\u0153uf dans le m\u00e9lange, puis ajouter le lait et la moiti\u00e9 de l\u2019eau.<\/li>\n<li>Fouetter au fouet \u00e9lectrique \u00e0 main jusqu\u2019\u00e0 ce que le m\u00e9lange soit beau et lisse. M\u00e9langer le reste de l\u2019eau et le beurre fondu. Le m\u00e9lange devrait avoir la consistance d\u2019une cr\u00e8me l\u00e9g\u00e8re.<\/li>\n<li>Si possible, laisser le m\u00e9lange reposer quelques heures ou une nuit.<\/li>\n<li>Faire chauffer une po\u00eale \u00e0 cr\u00eape ou une grande po\u00eale antiadh\u00e9sive \u00e0 feu moyen. Ajouter une noix de beurre et agiter la po\u00eale d\u2019un mouvement circulaire de fa\u00e7on \u00e0 ce que le beurre fondu couvre le fond. Soulever la po\u00eale du feu et ajouter une petite quantit\u00e9 de p\u00e2te \u00e0 cr\u00eape et faire tourner rapidement pour obtenir une couche tr\u00e8s mince de p\u00e2te couvrant tout le fond de la po\u00eale. Vous pouvez vous servir de couteau \u00e0 palette ou d\u2019une spatule pour \u00e9tendre le m\u00e9lange.<\/li>\n<li>Laisser cuire 2 minutes \u00e0 feu moyen, ou jusqu\u2019\u00e0 ce que la cr\u00eape glisse facilement dans la po\u00eale quand vous la remuez. Faire sauter la cr\u00eape et laisser cuire une minute ou deux de l\u2019autre c\u00f4t\u00e9.<\/li>\n<li>Faites sauter de nouveau la cr\u00eape et mettez y une tr\u00e8s petite noix de beurre, une mince tranche de jambon et une cuiller\u00e9e \u00e0 table de fromage r\u00e2p\u00e9 sur l\u2019autre moiti\u00e9 de la cr\u00eape.<\/li>\n<li>Plier la moiti\u00e9 non couverte de la cr\u00eape par-dessus la garniture et plier encore en deux et cuire \u00e0 feu doux jusqu\u2019\u00e0 ce que le fromage soit fondu.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La course de longue distance d\u2019hiver a quelque chose qui nous fait vouloir manger des [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-5324","post","type-post","status-publish","format-standard","hentry","category-recettes-de-course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galettes de sarrasin pour la longue distance - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Galettes de sarrasin pour la longue distance\",\"datePublished\":\"2015-02-20T16:41:52+00:00\",\"dateModified\":\"2015-02-20T17:16:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/\"},\"wordCount\":783,\"articleSection\":[\"Recettes de course\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/\",\"name\":\"Galettes de sarrasin pour la longue distance - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-02-20T16:41:52+00:00\",\"dateModified\":\"2015-02-20T17:16:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/galettes-de-sarrasin-pour-la-longue-distance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galettes de sarrasin pour la longue distance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galettes de sarrasin pour la longue distance - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Galettes de sarrasin pour la longue distance","datePublished":"2015-02-20T16:41:52+00:00","dateModified":"2015-02-20T17:16:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/"},"wordCount":783,"articleSection":["Recettes de course"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/","url":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/","name":"Galettes de sarrasin pour la longue distance - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2015-02-20T16:41:52+00:00","dateModified":"2015-02-20T17:16:37+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/galettes-de-sarrasin-pour-la-longue-distance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Galettes de sarrasin pour la longue distance"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=5324"}],"version-history":[{"count":3,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5324\/revisions"}],"predecessor-version":[{"id":5350,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5324\/revisions\/5350"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=5324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=5324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=5324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}