{"id":5250,"date":"2015-02-10T14:43:05","date_gmt":"2015-02-10T19:43:05","guid":{"rendered":"http:\/\/www.runottawa.ca\/?p=5250"},"modified":"2017-07-21T09:59:06","modified_gmt":"2017-07-21T13:59:06","slug":"spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/","title":{"rendered":"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ?"},"content":{"rendered":"<p>Par Elizabeth (Beth) Mansfield, PhD, MSc, RD<\/p>\n<p>L\u2019exercice et la vitamine D sont tous les deux importants pour la sant\u00e9 musculosquelettique et la sant\u00e9 des os. La vitamine D peut aussi avoir un effet b\u00e9n\u00e9fique sur certains types de cancer, en particulier le cancer colorectal et autres maladies se rattachant au syst\u00e8me immunitaire. L\u2019exposition de la peau aux rayons UVB du soleil stimule la production de la vitamine D dans la peau. M\u00eame si l\u2019exercice en plein air soit la cause d\u2019une \u00e9l\u00e9vation des niveaux de vitamine D chez plusieurs athl\u00e8tes, cet effet est saisonnier et il est probable qu\u2019on le voie seulement chez les coureurs plus jeunes, qui s\u2019entra\u00eenent \u00e0 l\u2019ext\u00e9rieur entre les mois d\u2019avril et de novembre, entre 10 heures et 16 heures. Pourquoi\u00a0?<\/p>\n<ol>\n<li>Au Canada, pendant la plus grande partie des mois d\u2019hiver, il n\u2019y a pas assez de radiation UVB en provenance du soleil pour permettre la production d\u2019une quantit\u00e9 efficace de vitamine D.<\/li>\n<li>Tout au long des mois d\u2019\u00e9t\u00e9, le moment d\u2019absorber un certain niveau de radiation UVB est pendant la journ\u00e9e \u2013 et beaucoup de coureurs s\u2019entra\u00eenent t\u00f4t le matin ou tard l\u2019apr\u00e8s-midi ou t\u00f4t en soir\u00e9e.<\/li>\n<li>La plupart des Canadiens ne consomment pas suffisamment de vitamine D dans leur r\u00e9gime alimentaire. Celle-ci se trouve dans la peau de poissons gras, dans quelques champignons, dans le lait fluide, les boissons au soja et quelques yogourts. \u00c0 moins que vous ne consommiez ces boissons et ces aliments tous les jours, il est probable que vous ne r\u00e9pondiez pas \u00e0 vos besoins de vitamine D tir\u00e9e des aliments.<\/li>\n<li>Les cellules de la peau vieillissent aussi \u2013 et la production de vitamine D de la peau diminue avec l\u2019\u00e2ge. La ligne de d\u00e9marcation semble \u00eatre l\u2019\u00e2ge de 50 ans.<\/li>\n<\/ol>\n<p><strong>Quels coureurs risquent le plus de ne pas avoir assez de vitamine D\u00a0?<\/strong><\/p>\n<ul>\n<li>Coureurs de plus de 50 ans. \u00c0 mesure qu\u2019on vieillit il se produit une r\u00e9duction de la production de vitamine D dans le corps. Si ce facteur est combin\u00e9 avec une diminution de la consommation de sources di\u00e9t\u00e9tiques de vitamine D, le risque d\u2019une insuffisance de vitamine D augmente.<\/li>\n<li>Coureurs ayant une intol\u00e9rance au lactose. L\u2019incapacit\u00e9 de dig\u00e9rer les sucres du lait signifie que la principale source de vitamine D \u2013 qu\u2019on trouve dans le lait \u2013 est absente du r\u00e9gime alimentaire.<\/li>\n<li>Coureurs \u00e0 la peau fonc\u00e9e. La capacit\u00e9 de produire de la vitamine D \u00e0 partir d\u2019une exposition au soleil varie en fonction de la pigmentation de la peau\u00a0; plus la peau est fonc\u00e9e, plus faible est la production de vitamine D.<\/li>\n<\/ul>\n<p><strong>Que devriez-vous faire\u00a0?<\/strong><\/p>\n<ul>\n<li>Les coureurs de plus de 50 ans devraient prendre un suppl\u00e9ment contenant au minimum 600 UI de vitamine D.<\/li>\n<li>Mettez \u00e0 votre r\u00e9gime des sources alimentaires de vitamine D pour aller chercher la vitamine D dont votre corps a besoin.<\/li>\n<li>Recherchez des aliments \u00e0 vitamine D ajout\u00e9e. Au Canada, le lait, la margarine et certains yogourts sont enrichis de vitamine D. Certains aliments comportent aussi des suppl\u00e9ments de vitamine D, comme certaines c\u00e9r\u00e9ales et jus d\u2019orange.<\/li>\n<li>Le poisson et les \u0153ufs sont d\u2019autres bonnes sources de vitamine D.<\/li>\n<\/ul>\n<p>Voici une liste de sources communes de vitamine D<\/p>\n<table width=\"316\">\n<tbody>\n<tr>\n<td width=\"251\"><strong>Aliments\/aliments enrichis<\/strong><\/td>\n<td style=\"text-align: center;\" width=\"65\"><strong>UI<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Boisson au soja enrichie* 250 ml (1 tasse)<\/td>\n<td style=\"text-align: center;\">120<\/td>\n<\/tr>\n<tr>\n<td>Margarine 5 ml (1 c. \u00e0 table)<\/td>\n<td style=\"text-align: center;\">60<\/td>\n<\/tr>\n<tr>\n<td>Lair 250 ml (1 tasse)<\/td>\n<td style=\"text-align: center;\">100<\/td>\n<\/tr>\n<tr>\n<td>Yogourt fait de lait enrichi\u00a0\u00a0 (175 ml)<\/td>\n<td style=\"text-align: center;\">80<\/td>\n<\/tr>\n<tr>\n<td>Jaune d\u2019\u0153uf, gros<\/td>\n<td style=\"text-align: center;\">40-50<\/td>\n<\/tr>\n<tr>\n<td><strong>Aliments enrichis\u00a0:<\/strong><\/td>\n<\/tr>\n<tr>\n<td>C\u00e9r\u00e9ales pr\u00eates \u00e0 manger enrichies de vitamine D<\/td>\n<td style=\"text-align: center;\">40<\/td>\n<\/tr>\n<tr>\n<td>Jus d\u2019Orange enrichi de vitamine D<\/td>\n<td style=\"text-align: center;\">120-140<\/td>\n<\/tr>\n<tr>\n<td><strong>Poisson\u00a0:<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Maquereau 90 g (3 oz.)<\/td>\n<td style=\"text-align: center;\">310<\/td>\n<\/tr>\n<tr>\n<td>Saumon, en bo\u00eete 90 g (3 oz.)<\/td>\n<td style=\"text-align: center;\">650<\/td>\n<\/tr>\n<tr>\n<td>Sardines, 1 bo\u00eete 100 g (3.75 oz.)<\/td>\n<td style=\"text-align: center;\">250<\/td>\n<\/tr>\n<tr>\n<td>Thon 90 g (3 oz.)<\/td>\n<td style=\"text-align: center;\">236<\/td>\n<\/tr>\n<tr>\n<td><strong>Suppl\u00e9ments\u00a0:<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Huile de foie de morue (1 c. \u00e0 table)<\/td>\n<td style=\"text-align: center;\">1360<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><em>Elizabeth (Beth) Mansfield, PhD, RD est nutritionniste agr\u00e9\u00e9e, sp\u00e9cialiste de la nutrition sportive et physiologiste de l\u2019exercice certifi\u00e9e chez\u00a0<a href=\"http:\/\/www.peakperformance.ca\/\">Peak Performance<\/a>\u00a0\u00e0 Ottawa. Beth \u00e9duque les athl\u00e8tes canadiens sur la nutrition sportive pour la sant\u00e9 et la performance.<\/em><\/p>\n<p>Copyright \u00a9 2014 Peak Performance. Tous droits reserves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Elizabeth (Beth) Mansfield, PhD, MSc, RD L\u2019exercice et la vitamine D sont tous les [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-5250","post","type-post","status-publish","format-standard","hentry","category-entrainement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ? - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ?\",\"datePublished\":\"2015-02-10T19:43:05+00:00\",\"dateModified\":\"2017-07-21T13:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/\"},\"wordCount\":701,\"articleSection\":[\"Entra\u00eenement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/\",\"name\":\"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ? - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2015-02-10T19:43:05+00:00\",\"dateModified\":\"2017-07-21T13:59:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ? - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ?","datePublished":"2015-02-10T19:43:05+00:00","dateModified":"2017-07-21T13:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/"},"wordCount":701,"articleSection":["Entra\u00eenement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/","url":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/","name":"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ? - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2015-02-10T19:43:05+00:00","dateModified":"2017-07-21T13:59:06+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/spot-sur-les-nutriments-pour-coureurs-prenez-vous-assez-de-vitamine-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Spot sur les nutriments pour coureurs \u2013 Prenez-vous assez de vitamine D ?"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=5250"}],"version-history":[{"count":3,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5250\/revisions"}],"predecessor-version":[{"id":5254,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/5250\/revisions\/5254"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=5250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=5250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=5250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}