{"id":3722,"date":"2014-10-20T23:33:10","date_gmt":"2014-10-21T03:33:10","guid":{"rendered":"http:\/\/www.runottawa.ca\/?p=3722"},"modified":"2014-10-20T23:33:10","modified_gmt":"2014-10-21T03:33:10","slug":"votre-budget-energetique-powerfuel","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/","title":{"rendered":"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122"},"content":{"rendered":"<p><strong>\u00a9<\/strong><strong>\u00a0<\/strong>Elizabeth (Beth) Mansfield, PhD,\u00a0<a href=\"http:\/\/www.peakperformance.ca\/\">Peak Performance<\/a>, Ottawa, ON<\/p>\n<p>Le mois dernier nous avons pr\u00e9sent\u00e9 le concept de donner \u00e0 votre corps un \u00ab\u00a0power fueling\u00a0\u00bb avec un budget \u00e9nerg\u00e9tique individualis\u00e9.\u00a0 Vous vous assurez ainsi d\u2019avoir assez d\u2019\u00e9nergie dans votre corps pour alimenter vos efforts d\u2019entra\u00eenement et de course.\u00a0 Ce mois-ci, nous allons voir comment calculer ce budget \u00e9nerg\u00e9tique.<\/p>\n<p>L\u2019\u00e9nergie dont vous avez besoin pour la vie et les sports provient des aliments et des boissons que vous prenez.\u00a0 Ce que vous n\u2019utilisez pas sur le champ est converti en graisse corporelle ou entrepos\u00e9 dans vos muscles.\u00a0 Le boni de vos programmes d\u2019entra\u00eenement \u00e0 la course est que cela augmente la capacit\u00e9 de vos cellules musculaires d\u2019entreposer l\u2019\u00e9nergie qui vient des aliments que vous consommez.\u00a0 Les muscles squelettiques entreposent de l\u2019\u00e9nergie sous la forme de glucides et de gras, et utilisent ensuite cette \u00e9nergie pendant des activit\u00e9s de haute intensit\u00e9 et d\u2019endurance.\u00a0 L\u2019\u00e9nergie est aussi entrepos\u00e9e comme graisse corporelle, qui devient une importante source d\u2019\u00e9nergie pendant un entra\u00eenement long et lent de distance (et pour les moments o\u00f9 vous vous passez de manger trop longtemps).<\/p>\n<p>Vos besoins pr\u00e9cis d\u2019\u00e9nergie vont d\u00e9pendre d\u2019un ensemble de diff\u00e9rents facteurs\u00a0: votre taille, vos g\u00e8nes, votre sexe et les demandes physiques de votre style de vie quotidien et de votre programme d\u2019entra\u00eenement.\u00a0 Votre niveau de forme physique agit \u00e9galement comme mod\u00e9rateur de ces besoins\u00a0; plus vous \u00eates en forme, moins d\u2019\u00e9nergie vous sera n\u00e9cessaire pour soutenir vos activit\u00e9s physiques habituelles.\u00a0 Cela veut \u00e9galement dire que, \u00e0 mesure que vous \u00eates plus en forme, vous pouvez devoir mieux contr\u00f4ler votre fourchette \u2013 \u00e0 moins d\u2019augmenter \u00e9galement l\u2019intensit\u00e9 et le volume de votre entra\u00eenement.<\/p>\n<p>Malgr\u00e9 tous ces facteurs, le processus en trois \u00e9tapes suivant a \u00e9t\u00e9 d\u00e9montr\u00e9 comme \u00e9tant tr\u00e8s pr\u00e9cis pour d\u00e9terminer combien d\u2019\u00e9nergie (en calories) vous est n\u00e9cessaire pour alimenter votre corps en fonction de ses besoins, compte tenu du style de vie et de l\u2019entra\u00eenement.<\/p>\n<p>Les trois \u00e9tapes sont\u00a0:<\/p>\n<ol>\n<li>D\u00e9terminer votre taux de m\u00e9tabolisme au repos.<\/li>\n<li>D\u00e9terminer votre niveau quotidien d\u2019activit\u00e9 physique.<\/li>\n<li>Calculer vos besoins \u00e9nerg\u00e9tiques quotidiens.<\/li>\n<\/ol>\n<p><strong>Premi\u00e8re \u00e9tape\u00a0: D\u00e9terminer votre taux de m\u00e9tabolisme au repos (RMR).<br \/>\n<\/strong>Votre RMR est la quantit\u00e9 de calories dont vous avez besoin simplement pour soutenir la vie dans votre corps.\u00a0 Votre RMR ne tient compte d\u2019aucun mouvement ou autres processus physiologiques qui n\u00e9cessitent plus d\u2019\u00e9nergie (par ex., manger, dig\u00e9rer, aller \u00e0 la toilette, promener le chien&#8230; vous avez compris l\u2019id\u00e9e&#8230;)\u00a0!<\/p>\n<p>Pour l\u2019\u00e9valuation du taux de m\u00e9tabolisme d\u2019une personne au repos, on recommande l\u2019usage d\u2019une calorim\u00e9trie indirecte.\u00a0 Dans des conditions o\u00f9 cette technique ne peut pas \u00eatre utilis\u00e9e, il existe des \u00e9quations qui peuvent pr\u00e9dire le RMR d\u2019athl\u00e8tes et de non athl\u00e8tes.<\/p>\n<p>Une des meilleures \u00e9quations pour les athl\u00e8tes (+\/- 220 calories) est la suivante.\u00a0 Vous aurez besoin de votre poids en kilogrammes et de votre hauteur en centim\u00e8tres.<\/p>\n<p><strong>RMR (kcal\/jour) = -857 + 9.0 x (poids en kg) + 11.7 x (hauteur en cm)<\/strong><\/p>\n<p>Donc, si vous faites 174 cm de hauteur et que vous pesez 76 kg, votre RMR est 1865.5 \u00b1220 kcal\/jour.<\/p>\n<p><strong>Deuxi\u00e8me \u00e9tape\u00a0: D\u00e9terminer votre niveau d\u2019activit\u00e9 physique quotidien.<br \/>\n<\/strong>Maintenant, utilisez le tableau suivant pour d\u00e9terminer votre niveau d\u2019activit\u00e9 physique quotidien.\u00a0<a href=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.28.01-PM.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3723\" src=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.28.01-PM.png\" alt=\"Screen Shot 2014-10-20 at 11.28.01 PM\" width=\"889\" height=\"280\" srcset=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.28.01-PM.png 889w, https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.28.01-PM-300x94.png 300w\" sizes=\"auto, (max-width: 889px) 100vw, 889px\" \/><\/a><\/p>\n<p>Donc, si vous \u00eates un coureur r\u00e9cr\u00e9atif qui s\u2019entra\u00eene pour un marathon et que vous faites 5 s\u00e9ances d\u2019exercice par semaine allant d\u2019une \u00e0 trois heures, disons que vous \u00eates tr\u00e8s actif.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Troisi\u00e8me \u00e9tape\u00a0: Calculer vos besoins \u00e9nerg\u00e9tiques pour diff\u00e9rents niveaux d\u2019activit\u00e9<br \/>\n<\/strong>Maintenant, \u00e0 l\u2019aide du tableau ci-dessous, il suffit de multiplier votre RMR par votre facteur d\u2019activit\u00e9 obtenu \u00e0 la deuxi\u00e8me \u00e9tape pour obtenir vos besoins \u00e9nerg\u00e9tiques quotidiens.<\/p>\n<p><a href=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.26.14-PM.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3724\" src=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.26.14-PM.png\" alt=\"Calculer vos besoins \u00e9nerg\u00e9tiques\" width=\"862\" height=\"384\" srcset=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.26.14-PM.png 862w, https:\/\/www.runottawa.ca\/wp-content\/uploads\/2014\/10\/Screen-Shot-2014-10-20-at-11.26.14-PM-300x133.png 300w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/a><\/p>\n<p>Une fois que vous connaissez vos besoins \u00e9nerg\u00e9tiques quotidiens, vous pouvez commencer \u00e0 les traduire en portions alimentaires.\u00a0 Revenez-nous le mois prochain pour pr\u00e9parer votre plan de nutrition PowerFuel\u2122 pour r\u00e9pondre \u00e0 vos besoins quotidiens d\u2019\u00e9nergie\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Au sujet de Beth Mansfield<\/strong><br \/>\n<em>Elizabeth (Beth) Mansfield, Ph.\u00a0D., est di\u00e9t\u00e9tiste autoris\u00e9e, sp\u00e9cialiste de la nutrition des athl\u00e8tes et physiologiste de l\u2019exercice certifi\u00e9e \u00e0<\/em><em>\u00a0<\/em><em><a href=\"http:\/\/www.peakperformance.ca\/\">Peak Performance<\/a>, \u00e0 Ottawa. Elle \u00e9duque les athl\u00e8tes canadiens en mati\u00e8re de nutrition ax\u00e9e sur la sant\u00e9 et la performance.<\/em><\/p>\n<p>Copyright \u00a9 2014 Peak Performance. Tous droits r\u00e9serv\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a9\u00a0Elizabeth (Beth) Mansfield, PhD,\u00a0Peak Performance, Ottawa, ON Le mois dernier nous avons pr\u00e9sent\u00e9 le concept [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-3722","post","type-post","status-publish","format-standard","hentry","category-recettes-de-course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122 - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122\",\"datePublished\":\"2014-10-21T03:33:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/\"},\"wordCount\":774,\"articleSection\":[\"Recettes de course\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/\",\"name\":\"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122 - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2014-10-21T03:33:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/votre-budget-energetique-powerfuel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122 - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122","datePublished":"2014-10-21T03:33:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/"},"wordCount":774,"articleSection":["Recettes de course"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/","url":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/","name":"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122 - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2014-10-21T03:33:10+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/votre-budget-energetique-powerfuel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Votre budget \u00e9nerg\u00e9tique PowerFuel\u2122"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/3722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=3722"}],"version-history":[{"count":2,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/3722\/revisions"}],"predecessor-version":[{"id":3726,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/3722\/revisions\/3726"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=3722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=3722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}