{"id":30817,"date":"2021-11-15T10:28:37","date_gmt":"2021-11-15T15:28:37","guid":{"rendered":"https:\/\/www.runottawa.ca\/?p=30817"},"modified":"2022-02-15T16:42:16","modified_gmt":"2022-02-15T21:42:16","slug":"quand-plaisir-rime-avec-entrainement","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/","title":{"rendered":"Quand plaisir rime avec entra\u00eenement"},"content":{"rendered":"<div id=\"contentsContainer\" class=\"style-scope qowt-page\">\n<div id=\"contents\" class=\"style-scope qowt-page\">\n<p id=\"E89\" class=\"x-scope qowt-word-para-1\"><span id=\"E90\" class=\"qowt-font3-Arial\">Marie-\u00c8ve <\/span><span id=\"E92\" class=\"qowt-font3-Arial\">Riou<\/span><span id=\"E94\" class=\"qowt-font3-Arial\"> <\/span><span id=\"E95\" class=\"qowt-font3-Arial\">a gentiment accept\u00e9 de nous parler de son groupe de course \u00e0 <\/span><span id=\"E96\" class=\"qowt-font3-Arial\"> Gatineau<\/span><span id=\"E97\" class=\"qowt-font3-Arial\">\u00a0<\/span><span id=\"E98\" class=\"qowt-font3-Arial\">: Course4Fun.<\/span><\/p>\n<p id=\"E99\" class=\"x-scope qowt-word-para-2\"><strong><span id=\"E100\" class=\"qowt-font3-Arial\">Comment le groupe Course4Fun <\/span><span id=\"E102\" class=\"qowt-font3-Arial\">a-t-il<\/span><span id=\"E104\" class=\"qowt-font3-Arial\"> \u00e9t\u00e9 form\u00e9? Comment son histoire a-t-elle commenc\u00e9?<\/span><\/strong><\/p>\n<p id=\"E105\" class=\"x-scope qowt-word-para-2\"><span id=\"E106\" class=\"qowt-font3-Arial\">J\u2019ai <\/span><span id=\"E107\" class=\"qowt-font3-Arial\">cr\u00e9\u00e9<\/span><span id=\"E108\" class=\"qowt-font3-Arial\"> le groupe Course4Fun apr\u00e8s avoir fait partie de plusieurs groupes de sport (<\/span><span id=\"E110\" class=\"qowt-font3-Arial\">spinning<\/span><span id=\"E112\" class=\"qowt-font3-Arial\">, yoga, club des grands maitres\u2026), mais c\u2019est l\u2019entraineuse d\u2019un groupe de triathlon \u00e0 Qu\u00e9bec qui m\u2019a particuli\u00e8rement inspir\u00e9e par son approche inclusive. C\u2019est par la suite que j\u2019ai d\u00e9cid\u00e9 de devenir entraineuse pour diff\u00e9rents cours (<\/span><span id=\"E113\" class=\"qowt-font3-Arial\">c.-\u00e0-d<\/span><span id=\"E114\" class=\"qowt-font3-Arial\">., marche nordique, <\/span><span id=\"E116\" class=\"qowt-font3-Arial\">P<\/span><span id=\"E117\" class=\"qowt-font3-Arial\">ilates<\/span><span id=\"E119\" class=\"qowt-font3-Arial\">, musculation) avec diff\u00e9rentes client\u00e8les. Puis, alors que je venais de d\u00e9m\u00e9nager en Outaouais dans l\u2019optique de <\/span><span id=\"E120\" class=\"qowt-font3-Arial\">faire<\/span><span id=\"E121\" class=\"qowt-font3-Arial\"> mes \u00e9tudes de doctorat en physiologie de l\u2019exercice, j\u2019ai eu <\/span><span id=\"E122\" class=\"qowt-font3-Arial\">envie <\/span><span id=\"E123\" class=\"qowt-font3-Arial\">de <\/span><span id=\"E124\" class=\"qowt-font3-Arial\">former<\/span><span id=\"E125\" class=\"qowt-font3-Arial\"> un groupe de course \u00e0 pied et d\u2019y apporter ma couleur. Tranquillement<\/span><span id=\"E126\" class=\"qowt-font3-Arial\">,<\/span><span id=\"E127\" class=\"qowt-font3-Arial\"> le groupe s\u2019est agrandi et de fil en aiguille<\/span><span id=\"E129\" class=\"qowt-font3-Arial\"> <\/span><span id=\"E131\" class=\"qowt-font3-Arial\">a permis \u00e0 des dizaines de personnes de d\u00e9buter et progresser en course \u00e0 pied de mani\u00e8re durable. Mon conjoint m\u2019a \u00e9galement rejoint dans cette aventure, lui qui fait maintenant partie int\u00e9grante de l\u2019organisation autant dans la planification des sorties, des voyages <\/span><span id=\"E132\" class=\"qowt-font3-Arial\">et des <\/span><span id=\"E133\" class=\"qowt-font3-Arial\">\u00ab\u00a0<\/span><span id=\"E134\" class=\"qowt-font3-Arial\">partys<\/span><span id=\"E135\" class=\"qowt-font3-Arial\">\u00a0\u00bb<\/span><span id=\"E136\" class=\"qowt-font3-Arial\">. De mon c\u00f4t\u00e9, j\u2019ai principalement la responsabilit\u00e9 de planifier les <\/span><span id=\"E137\" class=\"qowt-font3-Arial\">entra\u00eenements<\/span><span id=\"E138\" class=\"qowt-font3-Arial\"> ainsi que la progression des s\u00e9ances et les cycles d\u2019entra\u00eenements. Nous <\/span><span id=\"E139\" class=\"qowt-font3-Arial\">voulons <\/span><span id=\"E140\" class=\"qowt-font3-Arial\">avoir du <\/span><span id=\"E141\" class=\"qowt-font3-Arial\">\u00ab\u00a0<\/span><span id=\"E142\" class=\"qowt-font3-Arial\">fun<\/span><span id=\"E143\" class=\"qowt-font3-Arial\">\u00a0\u00bb<\/span><span id=\"E144\" class=\"qowt-font3-Arial\"> dans la pratique de la course \u00e0 pied, tout en \u00e9tant quand m\u00eame comp\u00e9titifs lorsqu\u2019il le faut et pers\u00e9v\u00e9rants dans les sessions d\u2019entra\u00eenements plus difficiles. Notre pratique est saine et progressive, du fait que nous varions les trajets et les s\u00e9ances d\u2019entra\u00eenement, tout en aidant les membres de l\u2019\u00e9quipe \u00e0 \u00eatre r\u00e9guliers en offrant trois cours par semaine.<\/span><\/p>\n<p id=\"E145\" class=\"x-scope qowt-word-para-2\"><strong><span id=\"E146\" class=\"qowt-font3-Arial\">Quel est l\u2019objectif du groupe? Qu\u2019est-ce qui vous diff\u00e9rencie des autres groupes?<\/span><\/strong><\/p>\n<p id=\"E147\" class=\"x-scope qowt-word-para-2\"><span id=\"E148\" class=\"qowt-font3-Arial\">L\u2019objectif du groupe est de courir tout en ayant du fun, d\u2019o\u00f9 le nom Course4Fun! Une partie du<\/span><span id=\"E149\" class=\"qowt-font3-Arial\"> \u00ab\u00a0<\/span><span id=\"E150\" class=\"qowt-font3-Arial\">fun<\/span><span id=\"E151\" class=\"qowt-font3-Arial\">\u00a0\u00bb<\/span><span id=\"E152\" class=\"qowt-font3-Arial\"> est de se fixer un objectif SMART (<\/span><span id=\"E153\" class=\"qowt-font3-Arial\">c.-\u00e0-d<\/span><span id=\"E154\" class=\"qowt-font3-Arial\">., sp\u00e9cifique, mesurable, attirant, r\u00e9aliste et <\/span><span id=\"E155\" class=\"qowt-font3-Arial\">temporel<\/span><span id=\"E156\" class=\"qowt-font3-Arial\">) pour se motiver et progresser individuellement et non en se comparant avec les autres. Par exemple, plusieurs membres du groupe se fixent l\u2019objectif de courir l\u2019une des courses de la fin de semaine des courses d\u2019Ottawa, du D\u00e9fi Entreprises, la course de l\u2019Arm\u00e9e et cette ann\u00e9e la <\/span><span id=\"E158\" class=\"qowt-font3-Arial\">Trail<\/span><span id=\"E160\" class=\"qowt-font3-Arial\"> du Grand-Duc dans la r\u00e9gion de Qu\u00e9bec.<\/span><\/p>\n<p id=\"E161\" class=\"x-scope qowt-word-para-2\"><span id=\"E162\" class=\"qowt-font3-Arial\">Ce qui nous diff\u00e9rencie des autres groupes est qu\u2019on \u00ab<\/span><span id=\"E163\" class=\"qowt-font3-Arial\">\u00a0fait de la rotation\u00a0<\/span><span id=\"E164\" class=\"qowt-font3-Arial\">\u00bb, c\u2019est-\u00e0-dire que les plus rapides reviennent chercher les moins rapides, de fa\u00e7on que le groupe soit coh\u00e9sif et qu\u2019on ne laisse jamais personne derri\u00e8re. Le groupe est donc tr\u00e8s inclusif \u2013 il faut seulement \u00eatre en mesure de courir 5<\/span><span id=\"E165\" class=\"qowt-font3-Arial\">\u00a0<\/span><span id=\"E166\" class=\"qowt-font3-Arial\">km en continu afin de se joindre au groupe.<\/span><\/p>\n<p id=\"E167\" class=\"x-scope qowt-word-para-2\"><span id=\"E168\" class=\"qowt-font3-Arial\">Une autre chose qui nous diff\u00e9rencie est que nous faisons de l\u2019entra\u00eenement crois\u00e9 \u00e0 longueur d\u2019ann\u00e9e, soit le v\u00e9lo et la natation l\u2019\u00e9t\u00e9 et du ski de fond<\/span><span id=\"E169\" class=\"qowt-font3-Arial\"> et <\/span><span id=\"E170\" class=\"qowt-font3-Arial\">de la raquette l\u2019hiver. Et <\/span><span id=\"E171\" class=\"qowt-font3-Arial\">selon l<\/span><span id=\"E172\" class=\"qowt-font3-Arial\">\u2019<\/span><span id=\"E173\" class=\"qowt-font3-Arial\">\u00e9tape o\u00f9 on en est dans le <\/span><span id=\"E174\" class=\"qowt-font3-Arial\">cycle d\u2019entra\u00eenement, on en profite <\/span><span id=\"E175\" class=\"qowt-font3-Arial\">\u00e9galement pour sortir de la ville et se donner un d\u00e9fi de randonn\u00e9e, par exemple aux <\/span>Adirondacks.<\/p>\n<\/div>\n<\/div>\n<div id=\"contentsContainer\" class=\"style-scope qowt-page\">\n<div id=\"contents\" class=\"style-scope qowt-page\">\n<p id=\"E177\" class=\"x-scope qowt-word-para-2\"><span id=\"E178\" class=\"qowt-font3-Arial\">Finalement, on a b\u00e2ti une petite famille ou l\u2019aspect social est hyper important. On veut que les gens se sentent bien et oublie les tracas de la vie quotidienne. On vise un esprit sain dans un corps sain!<\/span><\/p>\n<p id=\"E179\" class=\"x-scope qowt-word-para-2\"><strong><span id=\"E180\" class=\"qowt-font3-Arial\">Comment la pand\u00e9mie a-t-elle chang\u00e9 les habitudes du groupe?<\/span><\/strong><\/p>\n<p id=\"E181\" class=\"x-scope qowt-word-para-2\"><span id=\"E182\" class=\"qowt-font3-Arial\">Comme nous visons une pratique durable de l\u2019activit\u00e9 physique, au d\u00e9but de la pand\u00e9mie, nous avons d\u00fb nous adapter rapidement, soit <\/span><span id=\"E184\" class=\"qowt-font3-Arial\">passer<\/span><span id=\"E186\" class=\"qowt-font3-Arial\"> en mode virtuel. La p\u00e9riode d\u2019\u00e9chauffement ainsi que le plan d\u2019entra\u00eenement \u00e9taient donn\u00e9s <\/span><span id=\"E187\" class=\"qowt-font3-Arial\">sur<\/span><span id=\"E188\" class=\"qowt-font3-Arial\"> Zoom. Par la suite, tout le monde allait faire l\u2019entra\u00eenement \u00e0 l\u2019ext\u00e9rieur. <\/span><span id=\"E189\" class=\"qowt-font3-Arial\">\u00c0<\/span><span id=\"E190\" class=\"qowt-font3-Arial\"> une heure pr\u00e9cise<\/span><span id=\"E191\" class=\"qowt-font3-Arial\">,<\/span><span id=\"E192\" class=\"qowt-font3-Arial\"> on se rassemblait \u00e0 nouveau sur Zoom pour effectuer des exercices de musculation ou autres. Nous nous sommes adapt\u00e9s et avons choisi d\u2019ajouter davantage d\u2019entra\u00eenement musculaire afin de pr\u00e9parer notre retour. <\/span><span id=\"E194\" class=\"qowt-font3-Arial\">Pr\u00e8s<\/span><span id=\"E196\" class=\"qowt-font3-Arial\"> deux ans plus tard, nous nous retrouvons maintenant apr\u00e8s la pand\u00e9mie avec une superbe gang qui est fid\u00e8le au poste!<\/span><\/p>\n<p id=\"E197\" class=\"x-scope qowt-word-para-2\"><strong><span id=\"E198\" class=\"qowt-font3-Arial\">Qui se joint \u00e0 votre groupe? Que recherchent les personnes qui choisissent votre groupe?<\/span><\/strong><\/p>\n<p id=\"E199\" class=\"x-scope qowt-word-para-2\"><span id=\"E200\" class=\"qowt-font3-Arial\">C\u2019est tr\u00e8s variable. L\u2019\u00e2ge des membres du groupe varie entre 25 et 65<\/span><span id=\"E201\" class=\"qowt-font3-Arial\">\u00a0<\/span><span id=\"E202\" class=\"qowt-font3-Arial\">ans et comprend autant des hommes que des femmes. Nous remarquons que les gens sont dynamiques, positifs, respectueux de la vitesse des autres, curieux de se d\u00e9passer, enclins \u00e0 se challenger et \u00e0 relever de nouveaux d\u00e9fis. Les gens ont le d\u00e9sir de s\u2019am\u00e9liorer et <\/span><span id=\"E203\" class=\"qowt-font3-Arial\">souhaitent <\/span><span id=\"E204\" class=\"qowt-font3-Arial\">apprendre de nouvelles techniques ou exercices musculaires sp\u00e9cifiques. Bref, les gens sont ouverts d\u2019esprit! <\/span><\/p>\n<p id=\"E205\" class=\"x-scope qowt-word-para-2\"><span id=\"E206\" class=\"qowt-font2-TimesNewRoman\">\u00a0<\/span><strong><span id=\"E207\" class=\"qowt-font3-Arial\">Une anecdote \u00e0 nous raconter?<\/span><\/strong><\/p>\n<p id=\"E208\" class=\"x-scope qowt-word-para-2\"><span id=\"E209\" class=\"qowt-font3-Arial\">Je m\u2019en souviens encore comme si c\u2019\u00e9tait hier\u2026 c\u2019\u00e9tait en plein hiver, il faisait froid. J\u2019avais planifi\u00e9 faire des intervalles en c\u00f4te. La c\u00f4te choisie \u00e9tait en plein centre-ville de Hull. Alors que nous avions <\/span><span id=\"E210\" class=\"qowt-font3-Arial\">commenc\u00e9<\/span><span id=\"E211\" class=\"qowt-font3-Arial\"> notre entra\u00eenement, une personne qui nous \u00e9tait encore inconnue \u00e0 l\u2019\u00e9poque <\/span><span id=\"E212\" class=\"qowt-font3-Arial\">et <\/span><span id=\"E213\" class=\"qowt-font3-Arial\">vivant dans cette rue avait ouvert sa fen\u00eatre pour nous encourager. Quel bonheur! Comme si ce n\u2019\u00e9tait pas assez, apr\u00e8s quelques mont\u00e9es encore, il <\/span><span id=\"E214\" class=\"qowt-font3-Arial\">a mis <\/span><span id=\"E215\" class=\"qowt-font3-Arial\">son syst\u00e8me <\/span><span id=\"E216\" class=\"qowt-font3-Arial\">de son <\/span><span id=\"E217\" class=\"qowt-font3-Arial\">en marche avec la chanson<\/span><span id=\"E218\" class=\"qowt-font3-Arial\"> <\/span><span id=\"E219\" class=\"qowt-font3-Arial\">Eye of T<\/span><span id=\"E220\" class=\"qowt-font3-Arial\">he T<\/span><span id=\"E221\" class=\"qowt-font3-Arial\">iger<\/span><span id=\"E222\" class=\"qowt-font3-Arial\">! Je pense que pour la majorit\u00e9 d\u2019entre nous, cette soir\u00e9e reste m\u00e9morable!<\/span><\/p>\n<p id=\"E223\" class=\"x-scope qowt-word-para-3\"><strong><span id=\"E225\" class=\"qowt-font3-Arial\">O\u00f9 aimez-vous le plus courir?<\/span><\/strong><\/p>\n<p id=\"E226\" class=\"x-scope qowt-word-para-2\"><span id=\"E227\" class=\"qowt-font3-Arial\">En sentiers, sans aucun doute dans le <\/span><span id=\"E228\" class=\"qowt-font3-Arial\">p<\/span><span id=\"E229\" class=\"qowt-font3-Arial\">arc de la Gatineau. Il y a tant de sentiers \u00e0 d\u00e9couvrir et de possibilit\u00e9 de trajets. Nos favoris sont le sentier des loups et les chutes de <\/span><span id=\"E231\" class=\"qowt-font3-Arial\">Luskville<\/span><span id=\"E233\" class=\"qowt-font3-Arial\">.<\/span><\/p>\n<p id=\"E234\" class=\"x-scope qowt-word-para-4\"><span id=\"E235\" class=\"qowt-font3-Arial\">En route, sur le bord du canal Rideau. C\u2019est fou comme l\u2019eau, m\u00eame en pleine ville, d\u00e9tend et permet de se ressourcer!<\/span><\/p>\n<\/div>\n<\/div>\n<div id=\"contentsContainer\" class=\"style-scope qowt-page\">\n<div id=\"contents\" class=\"style-scope qowt-page\">\n<p id=\"E237\" class=\"x-scope qowt-word-para-2 x-scope qowt-word-para-2 x-scope qowt-word-para-2\"><span id=\"E238\" class=\"qowt-font3-Arial\">Si vous cherchez un groupe <\/span><span id=\"E239\" class=\"qowt-font3-Arial\">d\u2019entra\u00eenement <\/span><span id=\"E240\" class=\"qowt-font3-Arial\">qui sait s\u2019amuser tout en se d\u00e9passant, <\/span><span id=\"E241\" class=\"qowt-font3-Arial\">Course4Fun <\/span><span id=\"E242\" class=\"qowt-font3-Arial\">est ce qu\u2019il vous faut<\/span><span id=\"E243\" class=\"qowt-font3-Arial\">! <\/span><span id=\"E244\" class=\"qowt-font3-Arial\">Suivez le groupe sur <\/span><span id=\"E245\" class=\"qowt-font3-Arial\">Facebook (<\/span><a id=\"E246\" contenteditable=\"false\" href=\"https:\/\/www.facebook.com\/Course4Fun\" target=\"_blank\" rel=\"noopener\"><span id=\"E247\" class=\"qowt-font3-Arial qowt-stl-Lienhypertexte\">https:\/\/www.facebook.com\/Course4Fun<\/span><\/a><span id=\"E248\" class=\"qowt-font3-Arial\">) <\/span><span id=\"E249\" class=\"qowt-font3-Arial\">et<\/span><span id=\"E250\" class=\"qowt-font3-Arial\"> Instagram (<\/span><a id=\"E251\" contenteditable=\"false\" href=\"https:\/\/www.instagram.com\/course4fun\/\" target=\"_blank\" rel=\"noopener\"><span id=\"E252\" class=\"qowt-font3-Arial qowt-stl-Lienhypertexte\">https:\/\/www.instagram.com\/course4fun\/<\/span><\/a><span id=\"E253\" class=\"qowt-font3-Arial\">). Pour participer \u00e0 une activit\u00e9 du groupe, il suffit de vous inscrire en suivant les directives sur son site Web\u00a0<\/span><span id=\"E254\" class=\"qowt-font3-Arial\">: <\/span><a id=\"E255\" contenteditable=\"false\" href=\"https:\/\/course4fun.com\/nouvellement-inscrit\/\" target=\"_blank\" rel=\"noopener\"><span id=\"E256\" class=\"qowt-font3-Arial qowt-stl-Lienhypertexte\">https:\/\/course4fun.com\/nouvellement-inscrit<\/span><\/a><span id=\"E257\" class=\"qowt-font3-Arial\">\/.<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Marie-\u00c8ve Riou a gentiment accept\u00e9 de nous parler de son groupe de course \u00e0 Gatineau\u00a0: [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[60,107],"tags":[],"class_list":["post-30817","post","type-post","status-publish","format-standard","hentry","category-blogue-des-membres","category-communaute"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quand plaisir rime avec entra\u00eenement - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Quand plaisir rime avec entra\u00eenement\",\"datePublished\":\"2021-11-15T15:28:37+00:00\",\"dateModified\":\"2022-02-15T21:42:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/\"},\"wordCount\":1098,\"articleSection\":[\"Blogue des membres\",\"Communaut\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/\",\"name\":\"Quand plaisir rime avec entra\u00eenement - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2021-11-15T15:28:37+00:00\",\"dateModified\":\"2022-02-15T21:42:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/quand-plaisir-rime-avec-entrainement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand plaisir rime avec entra\u00eenement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand plaisir rime avec entra\u00eenement - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Quand plaisir rime avec entra\u00eenement","datePublished":"2021-11-15T15:28:37+00:00","dateModified":"2022-02-15T21:42:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/"},"wordCount":1098,"articleSection":["Blogue des membres","Communaut\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/","url":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/","name":"Quand plaisir rime avec entra\u00eenement - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2021-11-15T15:28:37+00:00","dateModified":"2022-02-15T21:42:16+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/quand-plaisir-rime-avec-entrainement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Quand plaisir rime avec entra\u00eenement"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/30817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=30817"}],"version-history":[{"count":1,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/30817\/revisions"}],"predecessor-version":[{"id":30818,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/30817\/revisions\/30818"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=30817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=30817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=30817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}