{"id":28172,"date":"2020-12-03T12:30:06","date_gmt":"2020-12-03T17:30:06","guid":{"rendered":"https:\/\/www.runottawa.ca\/?p=28172"},"modified":"2025-11-11T15:54:58","modified_gmt":"2025-11-11T20:54:58","slug":"les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir","status":"publish","type":"post","link":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/","title":{"rendered":"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">L\u2019hiver signifie que les temp\u00e9ratures chutent, que les surfaces durcissent et que le terrain devient in\u00e9gal. Ces conditions sont la recette parfaite pour subir des blessures si vous ne faites pas attention. Un muscle froid et tendu qu\u2019on force \u00e0 se contracter \u00e0 une intensit\u00e9 \u00e9lev\u00e9e est vuln\u00e9rable aux blessures. La course sur la glace et dans la neige active les muscles diff\u00e9remment que la course sur une surface plane. Votre corps doit alors compenser.\u00a0\u00a0<\/span><\/p>\n<p><b>1. Blessures \u00e0 l\u2019aine\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les blessures au groupe de muscles de l\u2019int\u00e9rieur de la cuisse, les adducteurs, sont courantes chez les coureurs en hiver. Les surfaces glissantes et le terrain in\u00e9gal peuvent vous faire perdre pied lorsque vous courrez. Si cela vous arrive, les muscles de l\u2019aine s\u2019\u00e9tirent trop et sont surcharg\u00e9s, ce qui peut causer une entorse ou m\u00eame une d\u00e9chirure.\u00a0 <\/span><\/p>\n<p><b>2. Entorses \u00e0 la cheville ou au genou\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Le fait de courir sur un terrain in\u00e9gal entra\u00eene l\u2019activation de vos stabilisateurs de la cheville, particuli\u00e8rement le muscle p\u00e9ronier et le muscle tibial post\u00e9rieur. Ces muscles servent \u00e0 la stabilit\u00e9 et au contr\u00f4le des mouvements. Lorsque vous courez sur une surface in\u00e9gale, vous transf\u00e9rez votre poids vers vos talons et les forces sont alors absorb\u00e9es par les stabilisateurs de votre cheville. L\u2019inversion et l\u2019\u00e9version r\u00e9p\u00e9t\u00e9es de la cheville lorsque vous courez dans les traces laiss\u00e9es par d\u2019autres personnes peuvent aussi causer des entorses ou des foulures.\u00a0\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.runottawa.ca\/fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43520 size-full\" src=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2020\/12\/TORW-2026-KMAG-leaderboard-728x90-1.png\" alt=\"\" width=\"1457\" height=\"181\" srcset=\"https:\/\/www.runottawa.ca\/wp-content\/uploads\/2020\/12\/TORW-2026-KMAG-leaderboard-728x90-1.png 1457w, https:\/\/www.runottawa.ca\/wp-content\/uploads\/2020\/12\/TORW-2026-KMAG-leaderboard-728x90-1-300x37.png 300w, https:\/\/www.runottawa.ca\/wp-content\/uploads\/2020\/12\/TORW-2026-KMAG-leaderboard-728x90-1-1024x127.png 1024w, https:\/\/www.runottawa.ca\/wp-content\/uploads\/2020\/12\/TORW-2026-KMAG-leaderboard-728x90-1-768x95.png 768w\" sizes=\"auto, (max-width: 1457px) 100vw, 1457px\" \/><\/a><\/p>\n<p><b>3. R\u00e9activation d\u2019une fasciite plantaire ou d\u2019une tendinite au tendon d\u2019Achille\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les surfaces glac\u00e9es et dures causent plus de stress aux pieds \u00e0 chaque pas. Ces forces sup\u00e9rieures sont ensuite absorb\u00e9es par l\u2019apon\u00e9vrose plantaire et au tendon d\u2019Achille.\u00a0\u00a0<\/span><\/p>\n<p><b>Comment pr\u00e9venir les blessures lorsque vous courez l\u2019hiver\u00a0:\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les coureurs manquent souvent de mobilit\u00e9 aux hanches et de force lat\u00e9rale. Pendant les mois d\u2019\u00e9t\u00e9, nous courons g\u00e9n\u00e9ralement en ligne droite et effectuons peu de mouvements lat\u00e9raux. Lorsque notre corps doit faire des mouvements lat\u00e9raux, nous sommes pr\u00e9dispos\u00e9s \u00e0 des blessures si nous n\u2019avons pas la force et la mobilit\u00e9 requises. Le fessier moyen est le principal muscle responsable de la stabilit\u00e9 lat\u00e9rale des hanches. En travaillant ce muscle ainsi que les muscles de votre tronc, vous pouvez \u00e9viter les blessures \u00e0 l\u2019aine. Il est aussi important d\u2019int\u00e9grer des exercices de mobilit\u00e9 des flexeurs de la hanche et des muscles de l\u2019aine puisque notre foul\u00e9e se raccourcit et varie en hiver. Cette m\u00e9canique de course modifi\u00e9e active davantage les flexeurs de la hanche. C\u2019est pourquoi il est primordial de prendre du temps pour leur assurer une bonne mobilit\u00e9.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous devez aussi id\u00e9alement investir dans une bonne paire de chaussures bien coussin\u00e9es et qui sont dot\u00e9es d\u2019un soutien et d\u2019une traction accrus. Comme la temp\u00e9rature des muscles est directement li\u00e9e \u00e0 leur rendement, habillez-vous de fa\u00e7on appropri\u00e9e. Faites un \u00e9chauffement dynamique, comprenant des exercices de mobilit\u00e9 et d\u2019activation, \u00e0 l\u2019int\u00e9rieur avant de sortir. Portez des v\u00eatements ad\u00e9quats pour minimiser la perte de chaleur \u00e0 la t\u00eate, aux mains et aux pieds.\u00a0\u00a0<\/span><\/p>\n<p><em><strong>\u00c0 propos de l\u2019auteur\u00a0:\u00a0<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Joanna\u00a0Taylor est une chiropraticienne sp\u00e9cialis\u00e9e dans les blessures li\u00e9es au sport. Elle est la propri\u00e9taire de <a href=\"https:\/\/kineticedgehg.com\/\">Kinetic Edge Health Group,<\/a> une clinique multidisciplinaire situ\u00e9e \u00e0 Ottawa, o\u00f9 on offre des services de chiropractie, de massage et de physioth\u00e9rapie. Elle est aussi la copropri\u00e9taire de <a href=\"https:\/\/www.facebook.com\/recoverrx613\/\">Recover Rx<\/a>, le premier studio de r\u00e9cup\u00e9ration pour les athl\u00e8tes modernes au Canada.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019hiver signifie que les temp\u00e9ratures chutent, que les surfaces durcissent et que le terrain devient [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-28172","post","type-post","status-publish","format-standard","hentry","category-entrainement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir - Run Ottawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenn Tuthill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/\"},\"author\":{\"name\":\"Jenn Tuthill\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"headline\":\"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir\",\"datePublished\":\"2020-12-03T17:30:06+00:00\",\"dateModified\":\"2025-11-11T20:54:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/\"},\"wordCount\":639,\"articleSection\":[\"Entra\u00eenement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/\",\"name\":\"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir - Run Ottawa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-12-03T17:30:06+00:00\",\"dateModified\":\"2025-11-11T20:54:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/\",\"name\":\"Run Ottawa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.runottawa.ca\\\/fr\\\/#\\\/schema\\\/person\\\/50a4cf696226bc1abdac0eb2e9865256\",\"name\":\"Jenn Tuthill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g\",\"caption\":\"Jenn Tuthill\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir - Run Ottawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/","twitter_misc":{"\u00c9crit par":"Jenn Tuthill","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/#article","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/"},"author":{"name":"Jenn Tuthill","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"headline":"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir","datePublished":"2020-12-03T17:30:06+00:00","dateModified":"2025-11-11T20:54:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/"},"wordCount":639,"articleSection":["Entra\u00eenement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/","url":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/","name":"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir - Run Ottawa","isPartOf":{"@id":"https:\/\/www.runottawa.ca\/fr\/#website"},"datePublished":"2020-12-03T17:30:06+00:00","dateModified":"2025-11-11T20:54:58+00:00","author":{"@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256"},"breadcrumb":{"@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.runottawa.ca\/fr\/les-trois-principales-blessures-que-les-coureurs-subissent-en-hiver-et-comment-les-prevenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.runottawa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Les trois principales blessures que les coureurs subissent en hiver et comment les pr\u00e9venir"}]},{"@type":"WebSite","@id":"https:\/\/www.runottawa.ca\/fr\/#website","url":"https:\/\/www.runottawa.ca\/fr\/","name":"Run Ottawa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.runottawa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.runottawa.ca\/fr\/#\/schema\/person\/50a4cf696226bc1abdac0eb2e9865256","name":"Jenn Tuthill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/906d803a81a1a97b077ea848ff2a30566a571f77a866c3b63aa7ffb38a5d5cf5?s=96&d=mm&r=g","caption":"Jenn Tuthill"}}]}},"_links":{"self":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/28172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/comments?post=28172"}],"version-history":[{"count":4,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/28172\/revisions"}],"predecessor-version":[{"id":43523,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/posts\/28172\/revisions\/43523"}],"wp:attachment":[{"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/media?parent=28172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/categories?post=28172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.runottawa.ca\/fr\/wp-json\/wp\/v2\/tags?post=28172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}